{"id":4598,"date":"2020-05-07T09:42:26","date_gmt":"2020-05-07T13:42:26","guid":{"rendered":"https:\/\/www.kangalou.com\/blog\/?p=4598"},"modified":"2024-03-15T11:47:50","modified_gmt":"2024-03-15T15:47:50","slug":"demenager-au-temps-de-la-covid-19-consignes-et-precautions-a-prendre","status":"publish","type":"post","link":"https:\/\/www.kangalou.com\/blog\/fr\/demenager-au-temps-de-la-covid-19-consignes-et-precautions-a-prendre\/","title":{"rendered":"D\u00e9m\u00e9nager au temps de la COVID-19? Consignes et pr\u00e9cautions \u00e0 prendre"},"content":{"rendered":"<p>La p\u00e9riode de location\u00a0semble\u00a0d\u00e9marrer\u00a0et\u00a0de\u00a0nombreuses\u00a0questions se posent en lien avec le d\u00e9m\u00e9nagement et la pand\u00e9mie de la COVID-19. Tout d\u2019abord,\u00a0Kangalou\u00a0suit\u00a0les recommandations et\u00a0les\u00a0mesures gouvernementales en privil\u00e9giant le\u00a0renouvellement\u00a0de\u00a0votre bail actuel si votre d\u00e9m\u00e9nagement\u00a0n\u2019est pas essentiel.\u00a0Cependant si\u00a0votre d\u00e9m\u00e9nagement \u00e9tait d\u00e9j\u00e0 pr\u00e9vu pour cette ann\u00e9e, voici\u00a0de\u00a0bonnes pratiques\u00a0\u00e0 adopter\u00a0pour\u00a0emm\u00e9nager dans votre\u00a0nouvel appart de\u00a0fa\u00e7on\u00a0s\u00e9curitaire :<\/p>\n<ul>\n<li>Si possible,\u00a0ayez recours\u00a0\u00e0\u00a0des\u00a0d\u00e9m\u00e9nageurs\u00a0professionnels. En effet, les services de d\u00e9m\u00e9nageurs sont consid\u00e9r\u00e9s comme\u00a0\u00e9tant\u00a0des\u00a0<a href=\"https:\/\/www.quebec.ca\/sante\/problemes-de-sante\/a-z\/coronavirus-2019\/fermeture-endroits-publics-commerces-services-covid19\/\">activit\u00e9s essentielles<\/a> et\u00a0demeurent\u00a0disponibles.\u00a0Ils\u00a0ont aussi re\u00e7u des recommandations\u00a0de la part de l\u2019Institut national de sant\u00e9 publique du Qu\u00e9bec (INSPQ)\u00a0afin de pr\u00e9venir les risques de propagation de la COVID-19.<\/li>\n<li>Dans le cas o\u00f9 vous devez effectuer le d\u00e9m\u00e9nagement vous-m\u00eame et sans l\u2019aide de professionnels, faites appel\u00a0uniquement \u00e0 vos\u00a0proches directs, soit ceux avec qui vous habitez actuellement.\u00a0Il faut\u00a0absolument\u00a0limiter le nombre de personnes pr\u00e9sentes, \u00e9viter d\u2019\u00eatre plusieurs personnes dans la m\u00eame pi\u00e8ce\u00a0et\u00a0se tenir \u00e0\u00a02 m\u00e8tres\u00a0de distance.<\/li>\n<li>Il est essentiel de bien communiquer avec votre futur propri\u00e9taire, veiller \u00e0 ce que le locataire de votre nouvel\u00a0appartement soit bien en\u00a0mesure de quitter\u00a0\u00e0 la date convenue.<\/li>\n<li>Demandez\u00a0aussi\u00a0au\u00a0propri\u00e9taire\u00a0de vous renseigner sur\u00a0l\u2019\u00e9tat de sant\u00e9 r\u00e9cent des locataires pr\u00e9c\u00e9dents.\u00a0Tel que mentionn\u00e9 dans\u00a0le\u00a0<a href=\"http:\/\/www.habitation.gouv.qc.ca\/fileadmin\/internet\/documents\/COVID-19-feuillet-demenagement.pdf\">guide de la Soci\u00e9t\u00e9 d\u2019habitation du Qu\u00e9bec (SHQ<\/a>)\u00a0\u201csi\u00a0une personne qui r\u00e9side ou r\u00e9sidait dans votre futur logement a souffert des sympt\u00f4mes de la COVID-19, contactez le service Info-Sant\u00e9 811 afin d\u2019explorer les solutions possibles\u201d.<\/li>\n<li>Pour la journ\u00e9e de d\u00e9m\u00e9nagement, communiquez avec le propri\u00e9taire ou l\u2019ancien locataire afin de\u00a0savoir\u00a0\u00e0 quel moment celui-ci quittera le logement. Organisez-vous pour effectuer le d\u00e9m\u00e9nagement lorsque le logement sera compl\u00e8tement vide. De plus, cela permettra d\u2019\u00e9viter de croiser le(s)\u00a0ancien(s)\u00a0locataire(s).<\/li>\n<li>Vous devez penser \u00e0 nettoyer votre logement actuel afin de le laisser dans un \u00e9tat impeccable pour le nouveau locataire. Ensuite vous devrez d\u00e9sinfecter avec pr\u00e9caution votre nouveau logement ! Prenez une solution hydro-alcoolique et assurez-vous de bien nettoyer les surfaces fr\u00e9quemment touch\u00e9es comme les poign\u00e9es de porte, les interrupteurs&#8230; Si vous d\u00e9m\u00e9nagez dans un appartement meubl\u00e9, n\u2019oubliez pas de d\u00e9sinfecter les meubles et \u00e9lectrom\u00e9nagers.<\/li>\n<li>Parce qu\u2019un d\u00e9m\u00e9nagement qui se passe bien est un d\u00e9m\u00e9nagement qui est bien pr\u00e9par\u00e9, planifi\u00e9 et organis\u00e9. N\u2019oubliez pas non plus les diff\u00e9rentes formalit\u00e9s \u00e0 pr\u00e9voir lorsqu\u2019on d\u00e9m\u00e9nage : changement d\u2019adresse aupr\u00e8s des services de t\u00e9l\u00e9phonie ou d\u2019internet, banque&#8230; Pensez aussi \u00e0 votre abonnement \u00e0 Hydro-Qu\u00e9bec, <a href=\"https:\/\/www.kangalou.com\/blog\/fr\/assurancelocataire-pourquoi\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00e0 souscrire une assurance habitation<\/a>. Pour plus d\u2019informations, consultez <a href=\"https:\/\/www.kangalou.com\/blog\/fr\/preparer-son-demenagement-comme-un-pro\/\" target=\"_blank\" rel=\"noopener noreferrer\">la <em>checklist<\/em> compl\u00e8te con\u00e7ue par Kangalou<\/a>.<\/li>\n<\/ul>\n<p>En raison du contexte particulier de la pand\u00e9mie, diff\u00e9rentes\u00a0\u00e9tapes\u00a0suppl\u00e9mentaires\u00a0sont \u00e0 respecter avant, pendant et apr\u00e8s\u00a0votre\u00a0d\u00e9m\u00e9nagement\u00a0cette ann\u00e9e.\u00a0Suivez\u00a0le\u00a0<a href=\"http:\/\/www.habitation.gouv.qc.ca\/fileadmin\/internet\/documents\/COVID-19-feuillet-demenagement.pdf\">guide de la Soci\u00e9t\u00e9 d\u2019habitation du Qu\u00e9bec (SHQ)<\/a> qui\u00a0r\u00e9capitule les bonnes pratiques sanitaires \u00e0 adopter pour les locataires qui devront d\u00e9m\u00e9nager\u00a0prochainement.\u00a0Prenez toutes les pr\u00e9cautions n\u00e9cessaires afin d\u2019\u00e9viter les risques de propagation de la COVID-19.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La p\u00e9riode de location\u00a0semble\u00a0d\u00e9marrer\u00a0et\u00a0de\u00a0nombreuses\u00a0questions se posent en lien avec le d\u00e9m\u00e9nagement et la pand\u00e9mie de la COVID-19. Tout d\u2019abord,\u00a0Kangalou\u00a0suit\u00a0les recommandations et\u00a0les\u00a0mesures gouvernementales en privil\u00e9giant le\u00a0renouvellement\u00a0de\u00a0votre bail actuel si votre d\u00e9m\u00e9nagement\u00a0n\u2019est pas essentiel.\u00a0Cependant si\u00a0votre d\u00e9m\u00e9nagement \u00e9tait d\u00e9j\u00e0 pr\u00e9vu pour cette ann\u00e9e, voici\u00a0de\u00a0bonnes pratiques\u00a0\u00e0 adopter\u00a0pour\u00a0emm\u00e9nager dans votre\u00a0nouvel appart de\u00a0fa\u00e7on\u00a0s\u00e9curitaire : Si possible,\u00a0ayez recours\u00a0\u00e0\u00a0des\u00a0d\u00e9m\u00e9nageurs\u00a0professionnels. En effet, les services [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":4641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4,7],"yst_prominent_words":[1804,1657,1801,1797,758,1787,1799,1795,29,79,75,1680,1798,81,177,1803,1800,1802,1796,1794],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/4598"}],"collection":[{"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=4598"}],"version-history":[{"count":5,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/4598\/revisions"}],"predecessor-version":[{"id":4647,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/4598\/revisions\/4647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/media\/4641"}],"wp:attachment":[{"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=4598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=4598"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/yst_prominent_words?post=4598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}