{"id":2876,"date":"2021-09-19T08:42:00","date_gmt":"2021-09-19T12:42:00","guid":{"rendered":"https:\/\/blog.kangalou.com\/?p=2876"},"modified":"2025-02-28T12:12:42","modified_gmt":"2025-02-28T17:12:42","slug":"la-colocation-qui-fait-quoi","status":"publish","type":"post","link":"https:\/\/www.kangalou.com\/blog\/fr\/la-colocation-qui-fait-quoi\/","title":{"rendered":"La colocation, qui fait quoi?"},"content":{"rendered":"<p>Pour plusieurs, la colocation a quelque chose de rassurant. Certains aiment tellement l\u2019exp\u00e9rience qu\u2019ils en font un mode de vie, heureux de faire de nouvelles rencontres et de partager leur quotidien.<\/p>\n<p>Parmi les motivations \u00e0 vivre en colocation, la premi\u00e8re est plus \u00e9vidente&nbsp;: \u00e9conomiser de l\u2019argent. Non seulement le loyer est alors divis\u00e9, mais aussi les d\u00e9penses associ\u00e9es au logement, telles que l\u2019\u00e9lectricit\u00e9, l\u2019Internet et l\u2019assurance habitation.<\/p>\n<p>Une autre raison peut \u00eatre de ne pas se retrouver seul. C\u2019est l\u2019occasion r\u00eav\u00e9e de passer plus de temps avec vos amis\u2026 ou de vous en faire de nouveaux! Il est toujours plaisant d\u2019\u00eatre entour\u00e9.<\/p>\n<p>Peu importe ce qui vous incitera \u00e0 vivre en colocation, <strong>l\u2019essentiel est de bien r\u00e9partir les t\u00e2ches<\/strong>. Quelles sont les responsabilit\u00e9s et les obligations de chacun\u2009? Pour vous aider \u00e0 y voir plus clair, voici un topo des <strong>principaux points \u00e0 consid\u00e9rer.<\/strong><\/p>\n<h2><strong>Qui paie le loyer\u2009?<\/strong><\/h2>\n<p>Bien s\u00fbr, un appartement, \u00e7a se paie. Cependant, v\u00e9rifiez bien la mention au bail puisque ces deux sc\u00e9narios pourraient se produire.<\/p>\n<ul>\n<li><strong>1<sup>er<\/sup> sc\u00e9nario<\/strong>&nbsp;: Si l\u2019obligation est conjointe ou qu\u2019aucune pr\u00e9cision n\u2019est apport\u00e9e sur le type d\u2019obligation, <strong>chaque coloc est tenu de payer sa part.<\/strong><\/li>\n<\/ul>\n<p>Attention&nbsp;: si le loyer n\u2019est pas pay\u00e9 dans sa totalit\u00e9 le jour convenu, d\u00e8s le lendemain en tant que locataire(s), vous \u00eates en d\u00e9faut de paiement. Si le retard de paiement d\u00e9passe trois semaines, votre proprio peut entamer des proc\u00e9dures aupr\u00e8s de la <a href=\"https:\/\/www.rdl.gouv.qc.ca\/\">R\u00e9gie du logement<\/a> afin d\u2019obtenir la r\u00e9siliation du bail.<\/p>\n<ul>\n<li><strong>2<sup>e<\/sup> sc\u00e9nario<\/strong>&nbsp;: Si les colocataires se sont \u00ab&nbsp;engag\u00e9s solidairement&nbsp;\u00bb, comme l\u2019indique la section H du bail, <strong>l\u2019un ou l\u2019autre devra alors payer le loyer dans sa totalit\u00e9<\/strong> si l\u2019un des autres ne r\u00e8gle pas sa part.<\/li>\n<\/ul>\n<h2><strong>Autres ententes \u00e0 pr\u00e9voir<\/strong><\/h2>\n<p>Il est bon de vous asseoir avec votre ou vos futurs colocs pour \u00e9tablir certains points, peut-\u00eatre m\u00eame de r\u00e9diger un contrat de colocation pour mettre tout \u00e7a noir sur blanc, plus officiel. On pr\u00e9voit&nbsp;:<\/p>\n<ul>\n<li>la division des chambres<\/li>\n<li>le partage des aires communes (temps, visite d\u2019amis, habitudes\u2026)<\/li>\n<li>l\u2019utilisation des biens communs (t\u00e9l\u00e9vision, sofa, laveuse-s\u00e9cheuse, po\u00eale, r\u00e9frig\u00e9rateur [\u00e0 chacun sa tablette\u2009!]\u2026)<\/li>\n<li>l\u2019administrateur (celui qui paiera les factures au nom de tous)<\/li>\n<li>les d\u00e9penses communes (Wi-Fi, \u00e9lectricit\u00e9, assurance habitation\u2026)<\/li>\n<li>les t\u00e2ches m\u00e9nag\u00e8res autres que pour la chambre de chacun (poubelle, balayeuse, salle de bain\u2026)<\/li>\n<li>l\u2019\u00e9picerie (\u00e0 chacun sa bouffe, ou cuisine commune)<\/li>\n<\/ul>\n<h2><strong>Et si l\u2019un des colocs souhaite partir avant la fin du bail<\/strong><\/h2>\n<p>Cela peut arriver pour diff\u00e9rentes raisons. Pour se faire remplacer, il lui faut obtenir l\u2019autorisation du propri\u00e9taire et de son ou ses colocataires pour:<\/p>\n<ol>\n<li><strong>Sous-louer sa partie<\/strong> pour le restant du bail, tout en demeurant solidairement responsable des obligations qui lui \u00e9taient propres (paiement du loyer, r\u00e9paration des dommages caus\u00e9s s\u2019il y a lieu\u2026)\u2009;<\/li>\n<li><strong>C\u00e9der ses droits<\/strong>, et ainsi \u00eatre lib\u00e9r\u00e9 de toutes obligations.<\/li>\n<\/ol>\n<p>Alors, maintenant pr\u00eat \u00e0 vivre cette belle aventure de la colocation\u2009?<\/p>\n<p><strong>En collaboration avec le blogue&nbsp;<\/strong><a href=\"http:\/\/bohos.ca\/\" target=\"_blank\" rel=\"noopener\"><strong>Bohos.ca<\/strong><\/a><\/p>\n<p><\/p>\n<p class=\"\"><a href=\"https:\/\/www.kangalou.com\/blog\/fr\/comment-choisir-le-ou-la-bonne-colocataire-pour-votre-appartement\/\">Comment choisir le ou la bonne colocataire pour ton appart\u2009?<\/a><\/p>\n<p class=\"\"><a href=\"https:\/\/www.kangalou.com\/blog\/fr\/les-5-regles-dor-de-la-colocation\/\">Les 5 r\u00e8gles d\u2019or de la colocation<\/a><\/p>\n<p class=\"\"><a href=\"https:\/\/www.kangalou.com\/blog\/fr\/avantages-colocation-vs-seul\/\">Les avantages d\u2019habiter en colocation<\/a><\/p>\n<p><\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour plusieurs, la colocation a quelque chose de rassurant. Certains aiment tellement l\u2019exp\u00e9rience qu\u2019ils en font un mode de vie, heureux de faire de nouvelles rencontres et de partager leur quotidien. Parmi les motivations \u00e0 vivre en colocation, la premi\u00e8re est plus \u00e9vidente&nbsp;: \u00e9conomiser de l\u2019argent. Non seulement le loyer est alors divis\u00e9, mais aussi [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":7424,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[11],"yst_prominent_words":[71,39,1343,159,75,688,85,718,655,1101,41,94],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/2876"}],"collection":[{"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=2876"}],"version-history":[{"count":17,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/2876\/revisions"}],"predecessor-version":[{"id":7428,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/2876\/revisions\/7428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/media\/7424"}],"wp:attachment":[{"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=2876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=2876"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.kangalou.com\/blog\/fr\/wp-json\/wp\/v2\/yst_prominent_words?post=2876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}